{"id":7772,"date":"2023-02-16T14:49:26","date_gmt":"2023-02-16T14:49:26","guid":{"rendered":"https:\/\/romember.me\/?post_type=portfolios&#038;p=7772"},"modified":"2024-04-29T15:22:13","modified_gmt":"2024-04-29T15:22:13","slug":"civil-wedding-in-tuscany","status":"publish","type":"portfolios","link":"https:\/\/romember.me\/it\/portfolio\/civil-wedding-in-tuscany\/","title":{"rendered":"Rosa e Adriano"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"7772\" class=\"elementor elementor-7772\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ae76ff elementor-section-height-min-height elementor-section-items-bottom elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"4ae76ff\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bff3a81\" data-id=\"bff3a81\" data-element_type=\"column\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4539a4 elementor-widget elementor-widget-artale-animated-text\" data-id=\"d4539a4\" data-element_type=\"widget\" data-settings=\"{&quot;artale_ext_is_fadeout_animation&quot;:&quot;true&quot;,&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation_velocity&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.6999999999999999555910790149937383830547332763671875,&quot;sizes&quot;:[]},&quot;artale_ext_is_fadeout_animation_direction&quot;:&quot;up&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"themegoods-animated-text text-alignment-center transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"400\" data-transition-duration=\"800\">\n\t\t<span>\n\t\tFuga d&#039;amore\t<\/span>\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-306cf0b elementor-widget elementor-widget-artale-animated-text\" data-id=\"306cf0b\" data-element_type=\"widget\" data-settings=\"{&quot;artale_ext_is_fadeout_animation&quot;:&quot;true&quot;,&quot;artale_ext_is_fadeout_animation_velocity&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.59999999999999997779553950749686919152736663818359375,&quot;sizes&quot;:[]},&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation_direction&quot;:&quot;up&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"themegoods-animated-text text-alignment-center transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"200\" data-transition-duration=\"800\">\n\t\t<h1>\n\t\tRosa e Adriano\t<\/h1>\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cb76f5 elementor-widget elementor-widget-artale-animated-text\" data-id=\"4cb76f5\" data-element_type=\"widget\" data-settings=\"{&quot;artale_ext_is_fadeout_animation&quot;:&quot;true&quot;,&quot;artale_ext_is_fadeout_animation_velocity&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.40000000000000002220446049250313080847263336181640625,&quot;sizes&quot;:[]},&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation_direction&quot;:&quot;up&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"themegoods-animated-text text-alignment-center transition-top overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"400\" data-transition-duration=\"800\">\n\t\t<span>\n\t\t14 settembre 2023\t<\/span>\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd200f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dd200f0\" data-element_type=\"section\" data-settings=\"{&quot;artale_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af1f2ac\" data-id=\"af1f2ac\" data-element_type=\"column\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72dd880 elementor-widget elementor-widget-artale-gallery-masonry\" data-id=\"72dd880\" data-element_type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"artale-gallery-masonry.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"artale-gallery-grid-content-wrapper do-masonry layout-artale-two-cols has_space\" data-cols=\"2\">\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/043_Roza-i-Adrian_DSC2326_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/043_Roza-i-Adrian_DSC2326_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/043_Roza-i-Adrian_DSC2326_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/043_Roza-i-Adrian_DSC2326_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/040_Roza-i-Adrian_DSC2315_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/040_Roza-i-Adrian_DSC2315_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/040_Roza-i-Adrian_DSC2315_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/040_Roza-i-Adrian_DSC2315_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/059_Roza-i-Adrian_DSC2431_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/059_Roza-i-Adrian_DSC2431_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/059_Roza-i-Adrian_DSC2431_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/059_Roza-i-Adrian_DSC2431_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/025_Roza-i-Adrian_DSC2295_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/025_Roza-i-Adrian_DSC2295_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/025_Roza-i-Adrian_DSC2295_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/025_Roza-i-Adrian_DSC2295_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/027_Roza-i-Adrian_DSC0890.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/027_Roza-i-Adrian_DSC0890-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/027_Roza-i-Adrian_DSC0890-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/027_Roza-i-Adrian_DSC0890-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/056_Roza-i-Adrian_DSC2410_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/056_Roza-i-Adrian_DSC2410_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/056_Roza-i-Adrian_DSC2410_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/056_Roza-i-Adrian_DSC2410_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/081_Roza-i-Adrian_DSC2529_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/081_Roza-i-Adrian_DSC2529_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/081_Roza-i-Adrian_DSC2529_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/081_Roza-i-Adrian_DSC2529_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/062_Roza-i-Adrian_DSC2442_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/062_Roza-i-Adrian_DSC2442_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/062_Roza-i-Adrian_DSC2442_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/062_Roza-i-Adrian_DSC2442_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/052_Roza-i-Adrian_DSC2375_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/052_Roza-i-Adrian_DSC2375_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/052_Roza-i-Adrian_DSC2375_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/052_Roza-i-Adrian_DSC2375_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/089_Roza-i-Adrian_DSC2556_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/089_Roza-i-Adrian_DSC2556_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/089_Roza-i-Adrian_DSC2556_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/089_Roza-i-Adrian_DSC2556_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/297_Roza-i-Adrian_DSC3880_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/297_Roza-i-Adrian_DSC3880_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/297_Roza-i-Adrian_DSC3880_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/297_Roza-i-Adrian_DSC3880_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/115_Roza-i-Adrian_DSC2821_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/115_Roza-i-Adrian_DSC2821_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/115_Roza-i-Adrian_DSC2821_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/115_Roza-i-Adrian_DSC2821_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/119_Roza-i-Adrian_DSC2737_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/119_Roza-i-Adrian_DSC2737_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/119_Roza-i-Adrian_DSC2737_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/119_Roza-i-Adrian_DSC2737_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/118_Roza-i-Adrian_DSC2733_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/118_Roza-i-Adrian_DSC2733_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/118_Roza-i-Adrian_DSC2733_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/118_Roza-i-Adrian_DSC2733_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/147_Roza-i-Adrian_DSC2948_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/147_Roza-i-Adrian_DSC2948_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/147_Roza-i-Adrian_DSC2948_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/147_Roza-i-Adrian_DSC2948_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/167_Roza-i-Adrian_DSC3019_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/167_Roza-i-Adrian_DSC3019_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/167_Roza-i-Adrian_DSC3019_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/167_Roza-i-Adrian_DSC3019_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/173_Roza-i-Adrian_DSC3064_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/173_Roza-i-Adrian_DSC3064_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/173_Roza-i-Adrian_DSC3064_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/173_Roza-i-Adrian_DSC3064_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/206_Roza-i-Adrian_DSC3288_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/206_Roza-i-Adrian_DSC3288_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/206_Roza-i-Adrian_DSC3288_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/206_Roza-i-Adrian_DSC3288_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/214_Roza-i-Adrian_DSC3496_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/214_Roza-i-Adrian_DSC3496_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/214_Roza-i-Adrian_DSC3496_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/214_Roza-i-Adrian_DSC3496_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/218_Roza-i-Adrian_DSC3339_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/218_Roza-i-Adrian_DSC3339_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/218_Roza-i-Adrian_DSC3339_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/218_Roza-i-Adrian_DSC3339_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/106_Roza-i-Adrian_DSC2777_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/106_Roza-i-Adrian_DSC2777_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/106_Roza-i-Adrian_DSC2777_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/106_Roza-i-Adrian_DSC2777_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/246_Roza-i-Adrian_DSC3578_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/246_Roza-i-Adrian_DSC3578_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/246_Roza-i-Adrian_DSC3578_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/246_Roza-i-Adrian_DSC3578_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/249_Roza-i-Adrian_DSC3585_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/249_Roza-i-Adrian_DSC3585_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/249_Roza-i-Adrian_DSC3585_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/249_Roza-i-Adrian_DSC3585_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/288_Roza-i-Adrian_DSC3835_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/288_Roza-i-Adrian_DSC3835_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/288_Roza-i-Adrian_DSC3835_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/288_Roza-i-Adrian_DSC3835_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/291_Roza-i-Adrian_DSC3842_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/291_Roza-i-Adrian_DSC3842_2-300x200.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/291_Roza-i-Adrian_DSC3842_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/291_Roza-i-Adrian_DSC3842_2-768x512.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/257_Roza-i-Adrian_DSC3639_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/257_Roza-i-Adrian_DSC3639_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/257_Roza-i-Adrian_DSC3639_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/257_Roza-i-Adrian_DSC3639_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/304_Roza-i-Adrian_DSC1361.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/304_Roza-i-Adrian_DSC1361-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/304_Roza-i-Adrian_DSC1361-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/304_Roza-i-Adrian_DSC1361-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/300_Roza-i-Adrian_DSC3910_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/300_Roza-i-Adrian_DSC3910_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/300_Roza-i-Adrian_DSC3910_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/300_Roza-i-Adrian_DSC3910_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/313_Roza-i-Adrian_DSC3914_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/313_Roza-i-Adrian_DSC3914_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/313_Roza-i-Adrian_DSC3914_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/313_Roza-i-Adrian_DSC3914_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/330_Roza-i-Adrian_DSC1471.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/330_Roza-i-Adrian_DSC1471-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/330_Roza-i-Adrian_DSC1471-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/330_Roza-i-Adrian_DSC1471-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/306_Roza-i-Adrian_DSC1376.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/306_Roza-i-Adrian_DSC1376-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/306_Roza-i-Adrian_DSC1376-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/306_Roza-i-Adrian_DSC1376-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols last  disable_all\" data-delay=\"300\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Rzym_Roza-i-Adrian_DSC4071-scaled.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Rzym_Roza-i-Adrian_DSC4071-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Rzym_Roza-i-Adrian_DSC4071-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Rzym_Roza-i-Adrian_DSC4071-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"gallery-grid-item artale-two-cols   disable_all\" data-delay=\"150\" data-minwidth=\"5000 slide-up\" data-move-y=\"60px\">\n\t\t\t\t\t\t\t<a class=\"artale_gallery_lightbox\" href=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/352_Roza-i-Adrian_DSC4153_2.jpg\" data-thumb=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/352_Roza-i-Adrian_DSC4153_2-200x300.jpg\" data-rel=\"tg_gallery72dd880\"  >\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/352_Roza-i-Adrian_DSC4153_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><noscript><img decoding=\"async\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/352_Roza-i-Adrian_DSC4153_2-768x1152.jpg\" class=\"lazy_masonry lazyload\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n<br class=\"clear\"\/>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-83e8f72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"83e8f72\" data-element_type=\"section\" data-settings=\"{&quot;artale_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d56afc1\" data-id=\"d56afc1\" data-element_type=\"column\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5adf8c1 elementor-widget__width-auto elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5adf8c1\" data-element_type=\"widget\" data-settings=\"{&quot;artale_ext_is_smoove&quot;:&quot;true&quot;,&quot;artale_ext_smoove_duration&quot;:800,&quot;artale_ext_smoove_scalex&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1000000000000000055511151231257827021181583404541015625,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_scaley&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.1000000000000000055511151231257827021181583404541015625,&quot;sizes&quot;:[]},&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_smoove_disable&quot;:1,&quot;artale_ext_smoove_rotatex&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_rotatey&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_rotatez&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_translatex&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_translatey&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_translatez&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_skewx&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_skewy&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;artale_ext_smoove_perspective&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1000,&quot;sizes&quot;:[]},&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ff1436 elementor-widget__width-inherit elementor-widget elementor-widget-artale-animated-text\" data-id=\"3ff1436\" data-element_type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"artale-animated-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"themegoods-animated-text text-alignment-center transition-bottom overflow-hidden\" data-delimiter=\"sentence\" data-transition=\"100\" data-transition-delay=\"200\" data-transition-duration=\"800\">\n\t\t<h2>\n\t\tAltri portafogli\t<\/h2>\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2872c7b elementor-section-full_width elementor-section-stretched animated-slow elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"2872c7b\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:400,&quot;artale_ext_is_background_parallax&quot;:&quot;false&quot;,&quot;artale_ext_is_background_on_scroll&quot;:&quot;false&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-168b19e\" data-id=\"168b19e\" data-element_type=\"column\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcd6398 elementor-widget elementor-widget-artale-portfolio-carousel\" data-id=\"fcd6398\" data-element_type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"artale-portfolio-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"portfolio-carousel-wrapper\">\n\t<div class=\"owl-carousel\" data-pagination=\"0\" data-autoplay=\"0\" data-timer=\"8000\" data-items=\"4\" data-stage-padding=\"0\" data-margin=\"20\">\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/695_Roma_Sofia-e-Andrea_R4_5548-Poprawione-NR-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/695_Roma_Sofia-e-Andrea_R4_5548-Poprawione-NR-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Sofia&amp;Andrea<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Reportage di matrimonio a Roma<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/sofia-andrea\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/10\/096_Anquillara-Sabazia_Michal-i-Ola_DSC5766-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/10\/096_Anquillara-Sabazia_Michal-i-Ola_DSC5766-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Aleksandra e Michal<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Servizio fotografico di matrimonio in EUR<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/eur\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/05\/26_VeneziaMagda-i-Bartek_DSC7397_20-kopia-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/05\/26_VeneziaMagda-i-Bartek_DSC7397_20-kopia-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Passeggiata mattutina a Venezia<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Sessione fotografica<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/morning-walk-in-venice\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Toskania_Aneta-i-Darek_DSC8415-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Toskania_Aneta-i-Darek_DSC8415-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Toscana romantica<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Sessione di fidanzamento in Toscana<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/romantic-tuscany\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/121_Sylwia-i-Sebastian_DSC3039-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/121_Sylwia-i-Sebastian_DSC3039-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Sylvia e Sebastiano<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Reportage di matrimonio a Castellabate<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/sylwia-sebastian\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2021\/03\/olivia-bauso-30UOqDM5QW0-unsplash-768x513.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2021\/03\/olivia-bauso-30UOqDM5QW0-unsplash-768x513.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Iwona &amp; Riccardo<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Il giorno del matrimonio ad Ariccia - video\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/iwona-riccardo\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Maja-i-Michal_slub-Serre-di-Rapolano_047-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Maja-i-Michal_slub-Serre-di-Rapolano_047-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Matrimonio civile e sessione di Maja e Michal<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Matrimonio civile in Toscana<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/maja-michal-civil-wedding-and-session\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Roma_Kamila-i-Rafal_DSC8615-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/Roma_Kamila-i-Rafal_DSC8615-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Kamila e Rafal a Roma<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Mini sessione fotografica<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/kamila-rafal-in-rome\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/291_Roza-i-Adrian_DSC3842_2-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/291_Roza-i-Adrian_DSC3842_2-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Rosa e Adriano<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Fuga d&#039;amore, matrimonio a Roma<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/civil-wedding-in-tuscany\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/cover2-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/cover2-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Karolina &amp; Pawel<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Mini Shooting a Venezia<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/karolina-pawel\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/Natalia-i-Mateusz_Circeo_47-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/Natalia-i-Mateusz_Circeo_47-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Natalia &amp; Matteo<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Servizio fotografico serale in spiaggia<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/photoshooting-on-the-beach\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/Mateusz-i-Paulina_fot-Anna-Sincini_DSC3146-2-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/Mateusz-i-Paulina_fot-Anna-Sincini_DSC3146-2-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Paulina &amp; Mateusz<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Camminando per le strade di Roma<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/paulina-mateusz\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/Marta-i-Slawek_Venezia_025-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/Marta-i-Slawek_Venezia_025-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Marta &amp; Slawek<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Mini Shooting a Venezia<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/marta-slawek\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/03\/Marta-i-Dawid_Rome_84_1-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/03\/Marta-i-Dawid_Rome_84_1-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Marta e David fuggono d&#039;amore<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Reportage da un matrimonio a Roma<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/marta-dawid\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/068_Portovenere_Ola-i-Luca_DSC2924-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2024\/02\/068_Portovenere_Ola-i-Luca_DSC2924-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Ol\u00e0 e Luca<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Fuga d&#039;amore a Portovenere, Liguria<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/ola-luca\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/10\/069_Rzym_Kala-i-Kamil_DSC0922-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/10\/069_Rzym_Kala-i-Kamil_DSC0922-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Kala e Kamil<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Fuga romantica e sessione fotografica a Roma<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/portfolio\/elopement-in-rome\/\"  ><\/a>\n\t\t\t<\/div>\n\t\t\t<div class=\"item\">\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-image\">\n\t\t\t\t\t\t<img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/Marco-e-Camilla_fot-Anna-Sincini_213-768x512.jpg\" alt=\"\" \/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/romember.me\/wp-content\/uploads\/2023\/02\/Marco-e-Camilla_fot-Anna-Sincini_213-768x512.jpg\" alt=\"\" \/><\/noscript>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-content\">\n\t\t\t\t\t\t<div class=\"overflow-inner\">\n\t\t\t\t\t\t\t<div class=\"overflow-text\">\n\t\t\t\t\t\t\t\t<h3 class=\"portfolio-carousel-title\">Marco &amp; Camilla<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"portfolio-carousel-subtitle\">Reportage dal giorno del matrimonio in Umbria<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/romember.me\/it\/single-portfolio-1\/\" target=\"&quot;_blank&quot;\" ><\/a>\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0271afd elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"0271afd\" data-element_type=\"widget\" data-settings=\"{&quot;artale_ext_link_sidemenu&quot;:&quot;false&quot;,&quot;artale_ext_link_fullmenu&quot;:&quot;false&quot;,&quot;artale_ext_is_sticky&quot;:&quot;false&quot;,&quot;artale_ext_is_scrollme&quot;:&quot;false&quot;,&quot;artale_ext_is_smoove&quot;:&quot;false&quot;,&quot;artale_ext_is_parallax_mouse&quot;:&quot;false&quot;,&quot;artale_ext_is_infinite&quot;:&quot;false&quot;,&quot;artale_ext_is_fadeout_animation&quot;:&quot;false&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/romember.me\/it\/portfolio-filterable\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visualizza tutto il portafoglio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Fuga d&#039;amore, matrimonio a Roma<\/p>","protected":false},"featured_media":7922,"comment_status":"closed","ping_status":"closed","template":"","portfolio_cat":[29],"class_list":["post-7772","portfolios","type-portfolios","status-publish","has-post-thumbnail","hentry","portfolio_cat-wedding-reportage"],"_links":{"self":[{"href":"https:\/\/romember.me\/it\/wp-json\/wp\/v2\/portfolios\/7772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/romember.me\/it\/wp-json\/wp\/v2\/portfolios"}],"about":[{"href":"https:\/\/romember.me\/it\/wp-json\/wp\/v2\/types\/portfolios"}],"replies":[{"embeddable":true,"href":"https:\/\/romember.me\/it\/wp-json\/wp\/v2\/comments?post=7772"}],"version-history":[{"count":23,"href":"https:\/\/romember.me\/it\/wp-json\/wp\/v2\/portfolios\/7772\/revisions"}],"predecessor-version":[{"id":8396,"href":"https:\/\/romember.me\/it\/wp-json\/wp\/v2\/portfolios\/7772\/revisions\/8396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/romember.me\/it\/wp-json\/wp\/v2\/media\/7922"}],"wp:attachment":[{"href":"https:\/\/romember.me\/it\/wp-json\/wp\/v2\/media?parent=7772"}],"wp:term":[{"taxonomy":"portfolio_cat","embeddable":true,"href":"https:\/\/romember.me\/it\/wp-json\/wp\/v2\/portfolio_cat?post=7772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}